{"id":707,"count":1,"description":"","link":"https:\/\/chandraalilijah.com\/index.php\/tag\/pizza-logs\/","name":"Pizza Logs","slug":"pizza-logs","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pizza Logs Archives - The Chandra Alilijah<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/chandraalilijah.com\/index.php\/tag\/pizza-logs\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pizza Logs Archives - The Chandra Alilijah\" \/>\n<meta property=\"og:url\" content=\"https:\/\/chandraalilijah.com\/index.php\/tag\/pizza-logs\/\" \/>\n<meta property=\"og:site_name\" content=\"The Chandra Alilijah\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@thechandraaa\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/chandraalilijah.com\\\/index.php\\\/tag\\\/pizza-logs\\\/\",\"url\":\"https:\\\/\\\/chandraalilijah.com\\\/index.php\\\/tag\\\/pizza-logs\\\/\",\"name\":\"Pizza Logs Archives - The Chandra Alilijah\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/chandraalilijah.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/chandraalilijah.com\\\/index.php\\\/tag\\\/pizza-logs\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/chandraalilijah.com\\\/index.php\\\/tag\\\/pizza-logs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/chandraalilijah.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pizza Logs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/chandraalilijah.com\\\/#website\",\"url\":\"https:\\\/\\\/chandraalilijah.com\\\/\",\"name\":\"The Chandra Alilijah\",\"description\":\"&quot;BECOMING THE NEXT ME&quot;\",\"publisher\":{\"@id\":\"https:\\\/\\\/chandraalilijah.com\\\/#\\\/schema\\\/person\\\/399e8fa9e89812922d48d295f5eb1e19\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/chandraalilijah.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/chandraalilijah.com\\\/#\\\/schema\\\/person\\\/399e8fa9e89812922d48d295f5eb1e19\",\"name\":\"chandraalilijah\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/chandraalilijah.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/img_3867-1.jpg?fit=1031%2C1200&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/chandraalilijah.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/img_3867-1.jpg?fit=1031%2C1200&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/chandraalilijah.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/img_3867-1.jpg?fit=1031%2C1200&ssl=1\",\"width\":1031,\"height\":1200,\"caption\":\"chandraalilijah\"},\"logo\":{\"@id\":\"https:\\\/\\\/i0.wp.com\\\/chandraalilijah.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/img_3867-1.jpg?fit=1031%2C1200&ssl=1\"},\"sameAs\":[\"https:\\\/\\\/chandraalilijah.com\",\"https:\\\/\\\/x.com\\\/thechandraaa\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCoMvPyO5V1SCx1WU4Gg3PlA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pizza Logs Archives - The Chandra Alilijah","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/chandraalilijah.com\/index.php\/tag\/pizza-logs\/","og_locale":"en_US","og_type":"article","og_title":"Pizza Logs Archives - The Chandra Alilijah","og_url":"https:\/\/chandraalilijah.com\/index.php\/tag\/pizza-logs\/","og_site_name":"The Chandra Alilijah","twitter_card":"summary_large_image","twitter_site":"@thechandraaa","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/chandraalilijah.com\/index.php\/tag\/pizza-logs\/","url":"https:\/\/chandraalilijah.com\/index.php\/tag\/pizza-logs\/","name":"Pizza Logs Archives - The Chandra Alilijah","isPartOf":{"@id":"https:\/\/chandraalilijah.com\/#website"},"breadcrumb":{"@id":"https:\/\/chandraalilijah.com\/index.php\/tag\/pizza-logs\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/chandraalilijah.com\/index.php\/tag\/pizza-logs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/chandraalilijah.com\/"},{"@type":"ListItem","position":2,"name":"Pizza Logs"}]},{"@type":"WebSite","@id":"https:\/\/chandraalilijah.com\/#website","url":"https:\/\/chandraalilijah.com\/","name":"The Chandra Alilijah","description":"&quot;BECOMING THE NEXT ME&quot;","publisher":{"@id":"https:\/\/chandraalilijah.com\/#\/schema\/person\/399e8fa9e89812922d48d295f5eb1e19"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/chandraalilijah.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/chandraalilijah.com\/#\/schema\/person\/399e8fa9e89812922d48d295f5eb1e19","name":"chandraalilijah","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/i0.wp.com\/chandraalilijah.com\/wp-content\/uploads\/2022\/08\/img_3867-1.jpg?fit=1031%2C1200&ssl=1","url":"https:\/\/i0.wp.com\/chandraalilijah.com\/wp-content\/uploads\/2022\/08\/img_3867-1.jpg?fit=1031%2C1200&ssl=1","contentUrl":"https:\/\/i0.wp.com\/chandraalilijah.com\/wp-content\/uploads\/2022\/08\/img_3867-1.jpg?fit=1031%2C1200&ssl=1","width":1031,"height":1200,"caption":"chandraalilijah"},"logo":{"@id":"https:\/\/i0.wp.com\/chandraalilijah.com\/wp-content\/uploads\/2022\/08\/img_3867-1.jpg?fit=1031%2C1200&ssl=1"},"sameAs":["https:\/\/chandraalilijah.com","https:\/\/x.com\/thechandraaa","https:\/\/www.youtube.com\/channel\/UCoMvPyO5V1SCx1WU4Gg3PlA"]}]}},"_links":{"self":[{"href":"https:\/\/chandraalilijah.com\/index.php\/wp-json\/wp\/v2\/tags\/707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chandraalilijah.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/chandraalilijah.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/chandraalilijah.com\/index.php\/wp-json\/wp\/v2\/posts?tags=707"},{"href":"https:\/\/chandraalilijah.com\/index.php\/wp-json\/wp\/v2\/pages?tags=707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}